{"id":517,"date":"2007-06-06T21:24:43","date_gmt":"2007-06-06T19:24:43","guid":{"rendered":"http:\/\/www.simdalom.com\/blog\/2007\/06\/06\/el-transporte-urbano-en-helsinki\/"},"modified":"2007-06-06T21:24:43","modified_gmt":"2007-06-06T19:24:43","slug":"el-transporte-urbano-en-helsinki","status":"publish","type":"post","link":"https:\/\/simdalom.com\/blog\/2007\/06\/06\/el-transporte-urbano-en-helsinki\/","title":{"rendered":"El transporte urbano en Helsinki"},"content":{"rendered":"<p>Ya que el geoposicionamiento est\u00e1 dando <a href=\"http:\/\/s.technorati.com\/panoramio?authority=a1&#038;language=\">tanto de qu\u00e9 hablar<\/a> estos d\u00edas, hablemos de ello. El uso que est\u00e1 dando a Google Maps la <a href=\"http:\/\/transport.wspgroup.fi\/hklkartta\/\">compa\u00f1\u00eda de transporte urbano de Helsinki<\/a> es impresionante. Para qu\u00e9 enviar un SMS con la palabra ESPERA y N\u00baPARADA al 7998 si puedes ver en tiempo real donde est\u00e1 tu autob\u00fas y en cuanto tiempo llegar\u00e1 a tu parada.<\/p>\n<p>Geolocalizaci\u00f3n en tiempo real de la l\u00edneas de autob\u00fas. Impresionante.<\/p>\n<div style=\"text-align: center\"><img decoding=\"async\" alt=\"Mapa transporte p\u00fablico Helsinki\" id=\"image641\" src=\"http:\/\/www.simdalom.com\/blog\/wp-content\/uploads\/2007\/06\/helsinki.jpg\" \/><\/div>\n<p>Otro post r\u00e1pido de \u00faltima hora del d\u00eda. Gracias por el enlace <a href=\"http:\/\/www.javiercanada.com\/\">Javier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya que el geoposicionamiento est\u00e1 dando tanto de qu\u00e9 hablar estos d\u00edas, hablemos de ello. El uso que est\u00e1 dando a Google Maps la compa\u00f1\u00eda de transporte urbano de Helsinki es impresionante. Para qu\u00e9 enviar un SMS con la palabra ESPERA y N\u00baPARADA al 7998 si puedes ver en tiempo real donde est\u00e1 tu autob\u00fas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-517","post","type-post","status-publish","format-standard","hentry","category-diseno"],"_links":{"self":[{"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/posts\/517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/comments?post=517"}],"version-history":[{"count":0,"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/posts\/517\/revisions"}],"wp:attachment":[{"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/media?parent=517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/categories?post=517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simdalom.com\/blog\/wp-json\/wp\/v2\/tags?post=517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}